{"id":72099,"date":"2022-03-07T06:34:37","date_gmt":"2022-03-07T06:34:37","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72048"},"modified":"2026-01-23T20:35:27","modified_gmt":"2026-01-23T20:35:27","slug":"savinside-die-methode-zur-optimierung-ihrer-long-tail-ausgaben","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/savinside-die-methode-zur-optimierung-ihrer-long-tail-ausgaben\/","title":{"rendered":"Savin\u2019side\u00ae, die Methode zur Optimierung Ihrer Long-Tail-Ausgaben"},"content":{"rendered":"<figure class=\"post-hero\">\n        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/01\/Savinside_-die-Methode-zur-Optimierung-Ihrer-Long-Tail-Ausgaben.jpeg\" alt=\"\" \/><br \/>\n      <\/figure>\n<div class=\"post-content\">\n<p>Die Optimierung von Long-Tail-Ausgaben ist ein wenig bekanntes Thema in Unternehmen. Normalerweise verwalten die Beschaffungsabteilungen ihre Haupt- und Mid-Tail-Eink\u00e4ufe auf strukturierte Weise, aber das ist nicht immer der Fall f\u00fcr Long-Tail-Ausgaben, die als nicht strategisch angesehen werden. Diese Art des Einkaufs macht jedoch bis zu 70% der versteckten Kosten in den Beschaffungsabteilungen aus. Gl\u00fccklicherweise gibt es eine Methode zur Optimierung der Verwaltung von Long-Tail-Ausgaben, die auf Datenanalyse, einem schlanken Beschaffungskonzept und einem agilen Rahmen basiert.<\/p>\n<h2>Die Herausforderung der Long-Tail-Ausgaben<\/h2>\n<p>Nach dem Pareto-Gesetz, das auch als 20-80-Gesetz bekannt ist, machen Long-Tail-Ausgaben 5% der Gesamtausgaben eines Unternehmens aus, aber 50% der gesamten Einkaufskategorien.<\/p>\n<p>Wendet man die Kraljic-Matrix an und kombiniert das finanzielle Risiko \u2013 das bei dieser Kategorie von Eink\u00e4ufen relativ gering ist \u2013 mit dem Gesamtrisiko, so lassen sich die \u201eLong Tail\u201c-Ausgaben in zwei Unterkategorien einteilen: sichere Eink\u00e4ufe (die ein geringes Risiko darstellen) und\/oder kritische Eink\u00e4ufe (die ein erhebliches Risiko beinhalten).<\/p>\n<p>In Bezug auf die \u201eLong Tail\u201c-Ausgaben ergeben sich daher zwei wichtige Fragen, f\u00fcr die eine geeignete Strategie angewandt werden sollte:<\/p>\n<ul>\n<li>\n<p>Erstens geht es darum, die Gesamtbetriebskosten (TCO) dieser K\u00e4ufe zu verstehen. Tats\u00e4chlich fallen bis zu 70% der versteckten Kosten bei der Verwaltung von Long-Tail-Ausgaben an. Diese Kosten stehen im Zusammenhang mit einer \u00fcberm\u00e4\u00dfigen Anzahl von Lieferpartnern, nicht abgeschlossenen K\u00e4ufen, fehlerhaften Prozessen, Fehler- und R\u00fcckgabemanagement usw.<\/p>\n<\/li>\n<li>\n<p>Gleichzeitig m\u00fcssen die Beschaffungsabteilungen auf die Sicherheit achten, insbesondere bei kritischen Eink\u00e4ufen. Zu diesem Zweck m\u00fcssen sie mit Lieferanten zusammenarbeiten, die die Qualit\u00e4t und Herkunft der Produkte, die Einhaltung von Normen und Vorschriften usw. garantieren k\u00f6nnen.<\/p>\n<\/li>\n<\/ul>\n<h2>Savin\u2019side\u00ae, eine \u201eLean-Agile\u201c Methode zur Optimierung von Long Tail Spend<\/h2>\n<p>Die Manutan-Gruppe hat eine Methode entwickelt, um ihre Key-Accounts bei der Optimierung von Long-Tail-Ausgaben zu unterst\u00fctzen. Savin\u2019side\u00ae wurde von Eink\u00e4ufern f\u00fcr andere Eink\u00e4ufer entwickelt und basiert auf Datenanalyse, einem Lean-Procurement-Ansatz und einem agilen methodischen Rahmen.<\/p>\n<p>Diese Strategie zielt darauf ab, die Gesamtbetriebskosten besser in den Griff zu bekommen und so das Management dieser Art von Einkauf durch sechs Optimierungshebel zu verbessern.<\/p>\n<h2>1. Rationalisierung des Lieferantenportfolios<\/h2>\n<p>Da bis zu 75% der Lieferanten eines Unternehmens auf Long-Tail-Ausgaben entfallen, verursachen sie erhebliche Verwaltungskosten. Diese umfassen Kosten f\u00fcr das Lieferantenmanagement (sch\u00e4tzungsweise durchschnittlich 1.000\u20ac\/Lieferant\/Jahr) und Transaktionskosten. Daher lohnt es sich, das Lieferantenportfolio zu verkleinern, indem man bestimmte Lieferanten (die z.B. nur geringe j\u00e4hrliche Ausgaben haben oder ein lokales Gebiet abdecken) durch einen einzigen H\u00e4ndler ersetzt, der eine breite Produktpalette anbietet.<\/p>\n<h2>2. Optimierung der Produktauswahl<\/h2>\n<p>Interne Kunden lassen sich bei der Wahl ihrer Long-Tail-Ausgaben nur selten leiten. Dies f\u00fchrt in der Regel zum Kauf von High-End-Produkten, d.h. hochwertigen, hochpreisigen Produkten von bekannten Marken. Dies ist jedoch bei einfachen Eink\u00e4ufen nicht immer angebracht und verursacht unn\u00f6tige Kosten. Die L\u00f6sung besteht also darin, die Auswahl der Produkte zu optimieren, indem man darauf achtet, dass sie den funktionalen Bed\u00fcrfnissen der internen Kunden entsprechen, um dieses Ph\u00e4nomen der \u201e\u00dcberqualit\u00e4t\u201c zu vermeiden.<\/p>\n<h2>3. Digitalisierung von Transaktionen<\/h2>\n<p>Wenn man bedenkt, dass 60% des Auftragsvolumens auf Long-Tail-Ausgaben entfallen, erscheint es zwingend notwendig, den Transaktionsprozess zu optimieren. Um dies zu erreichen, k\u00f6nnen die Beschaffungsabteilungen damit beginnen, den Procure-to-Pay-Prozess von der Produktauswahl bis zur Rechnungsstellung papierlos zu gestalten. Diese Strategie verbessert nicht nur die Effizienz innerhalb des Unternehmens, sondern bringt auch finanzielle Einsparungen und Umweltvorteile mit sich.<\/p>\n<h2>4. Optimierung der Logistik<\/h2>\n<p>Eine Vielzahl von Lieferanten und Auftr\u00e4gen f\u00fchrt zu einer gro\u00dfen Anzahl von Lieferungen, die den Einsatz verschiedener Mitarbeiter des Unternehmens (Sicherheitsdienst, Anlieferer, Lageristen usw.) erfordern, ohne dass ein wirklicher Mehrwert entsteht. Um die Produktivit\u00e4t aller Beteiligten zu steigern, k\u00f6nnen die Beschaffungsabteilungen die Prozesse f\u00fcr die Auslieferung und Bereitstellung der Produkte an die Nutzer durch verschiedene Dienstleistungen verbessern: personalisierte oder zeitgesteuerte Lieferungen, industrielle Verkaufsautomaten usw.<\/p>\n<h2>5. Einsatz einer Rahmenvereinbarung<\/h2>\n<p>Wenn die Beschaffungsrichtlinien in einem Unternehmen nicht ordnungsgem\u00e4\u00df eingehalten werden, f\u00fchrt dies zu direkten finanziellen Verlusten und zur Ausbreitung spontaner Ausgaben. Die Beschaffungsabteilungen m\u00fcssen sicherstellen, dass die im Vertrag mit einem Lieferpartner ausgehandelten Vorteile an allen Standorten des Unternehmens in vollem Umfang genutzt werden, und erforderlichenfalls die internen Kunden sensibilisieren (Informationen, Besuche vor Ort, Marketingkampagnen usw.).<\/p>\n<h2>6. Qualit\u00e4tsmanagement<\/h2>\n<p>Schlechte Qualit\u00e4t ist im gesamten Unternehmen verbreitet, was das Beschaffungsmanagement erschwert. Deshalb ist es von entscheidender Bedeutung, die Ursachen der festgestellten M\u00e4ngel zu beseitigen, um die Dienstleistungsquote zu verbessern.<\/p>\n<p>W\u00e4hrend die betriebliche Effizienz und die Kostensenkung zu den Priorit\u00e4ten der Beschaffungsabteilungen geh\u00f6ren, stellt die Optimierung der Long-Tail-Ausgaben einen gewaltigen Hebel f\u00fcr Ma\u00dfnahmen dar. Eine solche Strategie erinnert an Lean Procurement: kontinuierliches Aufsp\u00fcren von \u201eVerschwendung\u201c, hin zur Wertsch\u00f6pfung.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Optimierung von Long-Tail-Ausgaben ist ein wenig bekanntes Thema in Unternehmen. Normalerweise verwalten die Beschaffungsabteilungen ihre Haupt- und Mid-Tail-Eink\u00e4ufe auf strukturierte Weise, aber das ist nicht immer der Fall f\u00fcr Long-Tail-Ausgaben, die als nicht strategisch angesehen werden. Diese Art des Einkaufs macht jedoch bis zu 70% der versteckten Kosten in den Beschaffungsabteilungen aus. Gl\u00fccklicherweise gibt es eine Methode zur Optimierung&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":57039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-72099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intelligentes-und-effizientes-arbeiten"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72099"}],"version-history":[{"count":1,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72099\/revisions"}],"predecessor-version":[{"id":73175,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72099\/revisions\/73175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/57039"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}