{"id":72106,"date":"2022-03-24T07:42:52","date_gmt":"2022-03-24T07:42:52","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72054"},"modified":"2026-01-23T20:35:22","modified_gmt":"2026-01-23T20:35:22","slug":"nachhaltige-beschaffung-engagement-und-greifbarer-nutzen","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/nachhaltiger-arbeitsplatz\/nachhaltige-beschaffung-engagement-und-greifbarer-nutzen\/","title":{"rendered":"Nachhaltige Beschaffung: Engagement und greifbarer Nutzen"},"content":{"rendered":"<figure class=\"post-hero\">\n        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/01\/Nachhaltige_Beschaffung_Engagement_und_greifbarer_Nutzen.png\" alt=\"\" \/><br \/>\n      <\/figure>\n<div class=\"post-content\">\n<p><b>Zunehmend strengere Vorschriften und der Druck verschiedener Stakeholder haben die nachhaltige Beschaffung zu einem hei\u00dfen Thema f\u00fcr Unternehmen gemacht, sowohl auf der Einkaufs- als auch auf der Beschaffungsseite der Betriebe.<\/b> Das EcoVadis (Eine globale Plattform zur Bereitstellung von Nachhaltigkeitsratings f\u00fcr Unternehmen und kollaborativen Tools zur Verbesserung der CSR-Leistung) Sustainable Procurement Barometer 2019 untersucht den aktuellen Stand der nachhaltigen Beschaffung in globalen Unternehmen und zeigt auf, wie sie davon profitieren.<\/p>\n<h2>Nachhaltige Beschaffung: Eine echte Verpflichtung<\/h2>\n<p>Globale Unternehmen engagieren sich zunehmend f\u00fcr eine nachhaltige Beschaffung, was insbesondere im Hinblick auf die gro\u00dfen Herausforderungen f\u00fcr die Beschaffungsabteilungen (Einhaltung von Vorschriften, Risiken und Kosten) relevant ist. Zum Beweis: <b>81% der f\u00fcr das Barometer befragten Unternehmen geben an, dass das Engagement ihres Unternehmens f\u00fcr eine nachhaltige Beschaffung in den letzten drei Jahren zugenommen hat.<\/b><\/p>\n<p>Bei den Lieferanten sind <b>ethische \u00dcberlegungen der wichtigste Motivationsfaktor<\/b>. Fast die H\u00e4lfte der Lieferanten, die sich f\u00fcr einen nachhaltigen Beschaffungsansatz engagieren, denken nicht nur an ihr Leitbild, sondern auch an die Verbesserung der Welt und ihrer Gemeinschaft. Andere bleiben nat\u00fcrlich pragmatischer und gehen dieses Engagement aus finanziellen Gr\u00fcnden ein, um zu \u00fcberleben oder um regelkonformer zu werden.<\/p>\n<p>Wie Sie wissen, ist die nachhaltige Beschaffung im Laufe der Jahre zu einer gro\u00dfen Herausforderung in der wirtschaftlichen Landschaft geworden.<\/p>\n<h2>Die sieben wichtigsten Vorteile einer nachhaltigen Beschaffung<\/h2>\n<p>Obwohl es nicht einfach ist, den Return on Investment eines nachhaltigen Beschaffungsansatzes zu messen, waren sich die in dieser Studie befragten Unternehmen \u00fcber eine Reihe von konkreten Vorteilen einig:<\/p>\n<ol>\n<li>\n<p><b>Bessere Risikokontrolle<\/b>, die eine der Hauptpriorit\u00e4ten der Beschaffungsabteilungen anspricht.<\/p>\n<\/li>\n<li>\n<p><b>Reduzierte Kosten<\/b>, was eine weitere der Hauptpriorit\u00e4ten f\u00fcr Beschaffungsabteilungen adres- siert.<\/p>\n<\/li>\n<li>\n<p><b>F\u00f6rderung von Innovation und Differenzierung<\/b> durch neue Produkte oder Dienstleistungen.<\/p>\n<\/li>\n<li>\n<p><b>Gesteigerter Umsatz<\/b>, unabh\u00e4ngig davon, ob dies mit dem Ruf des Unternehmens oder seinem Engagement f\u00fcr die Anpassung an die neuen ethischen, sozialen und \u00f6kologischen Anforde- rungen der Kunden zusammenh\u00e4ngt.<\/p>\n<\/li>\n<li>\n<p><b>Verbesserte Beschaffungsindikatoren<\/b> in Bezug auf das Management von Ausgaben, Qualit\u00e4t und Lieferungen.<\/p>\n<\/li>\n<li>\n<p><b>Verbesserte nicht-finanzielle Ratings<\/b>: einschlie\u00dflich des Dow Jones Sustainability Index und Vigeo-Ratings.<\/p>\n<\/li>\n<li>\n<p><b>Verbesserte Talentakquise und -bindung<\/b>.<\/p>\n<\/li>\n<\/ol>\n<p>Diese Vorteile sind umso auff\u00e4lliger bei Unternehmen, die als \u201ereif\u201c gelten, wenn es um nachhaltige Beschaffung geht. Tats\u00e4chlich nennen 88% (im Vergleich zu 55% der \u201enicht reifen\u201c Unternehmen) die Risikoreduzierung als einen wichtigen Vorteil. Ebenso nennen 53% (im Vergleich zu 21% der \u201enicht reifen\u201c Unternehmen) verbesserte Beschaffungsindikatoren als weiteren wichtigen Vorteil. Dies ist eindeutig ein signifikanter Unterschied!<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Zunehmend strengere Vorschriften und der Druck verschiedener Stakeholder haben die nachhaltige Beschaffung zu einem hei\u00dfen Thema f\u00fcr Unternehmen gemacht, sowohl auf der Einkaufs- als auch auf der Beschaffungsseite der Betriebe. Das EcoVadis (Eine globale Plattform zur Bereitstellung von Nachhaltigkeitsratings f\u00fcr Unternehmen und kollaborativen Tools zur Verbesserung der CSR-Leistung) Sustainable Procurement Barometer 2019 untersucht den aktuellen Stand der nachhaltigen Beschaffung in&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":57045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-72106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachhaltiger-arbeitsplatz"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72106"}],"version-history":[{"count":1,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72106\/revisions"}],"predecessor-version":[{"id":73169,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72106\/revisions\/73169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/57045"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}