{"id":72355,"date":"2023-05-24T09:00:02","date_gmt":"2023-05-24T09:00:02","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72195"},"modified":"2026-02-12T11:39:29","modified_gmt":"2026-02-12T11:39:29","slug":"wie-beginnt-man-eine-kreislaufwirtschaftsstrategie-und-wie-implementiert-man","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/nachhaltiger-arbeitsplatz\/wie-beginnt-man-eine-kreislaufwirtschaftsstrategie-und-wie-implementiert-man\/","title":{"rendered":"Wie beginnt man eine Kreislaufwirtschaftsstrategie und wie implementiert man sie im Unternehmen?"},"content":{"rendered":"<figure class=\"post-hero\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-73684 size-full\" src=\"\/wp-content\/uploads\/2023\/05\/Wie_beginnt_man_eine_Kreislaufwirtschaftsstrategie_und_wie_implementiert_man_sie_im_Unternehmen.png\" alt=\"\" width=\"717\" height=\"478\" srcset=\"\/wp-content\/uploads\/2023\/05\/Wie_beginnt_man_eine_Kreislaufwirtschaftsstrategie_und_wie_implementiert_man_sie_im_Unternehmen.png 717w, \/wp-content\/uploads\/2023\/05\/Wie_beginnt_man_eine_Kreislaufwirtschaftsstrategie_und_wie_implementiert_man_sie_im_Unternehmen-300x200.png 300w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/><\/figure>\n<div class=\"post-content\">\n<p>Um den weltweiten Herausforderungen der nachhaltigen Entwicklung und des Umweltschutzes gerecht zu werden, entwerfen die Unternehmen ihre <a href=\"https:\/\/www.manutan.de\/de\/oid\/csr-ansatz\">CSR-Strategie<\/a> (Corporate Social Responsibility) und priorisieren diese sogar. Einer der wichtigsten Hebel f\u00fcr ein solches Vorgehen ist das wachsende Interesse an der <b>Kreislaufwirtschaft<\/b>. Und das aus gutem Grund, denn die NRO Circle Economy behauptet, dass ein Fokus auf die Kreislaufwirtschaft die Treibhausgasemissionen um bis zu 39% reduzieren und die globale Erw\u00e4rmung auf 2 \u00b0C begrenzen k\u00f6nnten. Dieses Konzept, das im Gegensatz zur linearen Wegwerfwirtschaft steht, bietet den Unternehmen zahlreiche M\u00f6glichkeiten, Geld zu sparen und gleichzeitig effizienter zu werden. Um solche Vorteile zu erzielen, muss eine echte Kreislaufwirtschaftsstrategie umgesetzt werden, wobei die wichtigsten Schritte und Expertenratschl\u00e4ge zu beachten sind.<\/p>\n<h2>Was versteht man unter Kreislaufwirtschaft?<\/h2>\n<blockquote><p>Die Vereinten Nationen geben eine umfassende Definition der Kreislaufwirtschaft: \u201eDie Kreislaufwirtschaft ist laut Definition der Brundtland-Kommission ein System der Produktion, des Austauschs und des Teilens, das sozialen Fortschritt, die Erhaltung des Naturkapitals und wirtschaftliche Entwicklung erm\u00f6glicht. Ihr Ziel ist es, das Wirtschaftswachstum von der Ausbeutung nat\u00fcrlicher Ressourcen zu entkoppeln, indem innovative Produkte, Dienstleistungen, Gesch\u00e4ftsmodelle und \u00f6ffentliche Ma\u00dfnahmen entwickelt werden, die alle Str\u00f6me w\u00e4hrend des gesamten Lebenszyklus eines Produkts oder einer Dienstleistung ber\u00fccksichtigen. Dieses Modell basiert auf der optimalen Nutzung von Ressourcen und der Schaffung positiver Wertsch\u00f6pfungskreisl\u00e4ufe. Es konzentriert sich auf neue Design-, Produktions- und Verbrauchsmethoden, die Verl\u00e4ngerung der Lebensdauer von Produkten sowie die Wiederverwendung und das Recycling von Komponenten.\u201c<\/p><\/blockquote>\n<h2>1. Sein eigenes Gesch\u00e4ftsmodell aus einem anderen Blickwinkel betrachten<\/h2>\n<p>Der erste Schritt zur Entwicklung einer Strategie der Kreislaufwirtschaft im Unternehmen besteht darin, die gesamte Wertsch\u00f6pfungskette zu analysieren, um die Grenzen des bestehenden linearen Wirtschaftsmodells zu erkennen.<\/p>\n<p>Justine Laurent, Gesch\u00e4ftsf\u00fchrerin von Circulab, einem unabh\u00e4ngigen Designstudio und einer Agentur f\u00fcr Strategieberatung, erkl\u00e4rt: \u201eZuallererst muss man die Gesch\u00e4ftst\u00e4tigkeit seines Unternehmens mit Abstand betrachten und die Probleme verstehen, die mit der linearen Wirtschaft einhergehen. Dies kann durch einen Mangel an verf\u00fcgbaren Ressourcen (Rohstoffe, Energie usw.), ein \u00fcberm\u00e4\u00dfiges Abfallaufkommen, eine begrenzte Produktlebensdauer usw. gekennzeichnet sein. Auf diese Weise wird den Beteiligten schnell klar, wie wichtig die Einf\u00fchrung einer Kreislaufwirtschaft f\u00fcr die Nachhaltigkeit ihres Gesch\u00e4ftsmodells ist.\u201c<\/p>\n<p>Unternehmen, die einen solchen Ansatz verfolgen wollen, m\u00fcssen ihr System kartieren. Diese Vorab-Diagnose erm\u00f6glicht es ihnen, Risiken und potenzielle Chancen zu erkennen. Denn man darf nicht vergessen, dass die Kreislaufwirtschaft in erster Linie eine Antwort auf ein Problem ist. Es geht nicht darum, die Kreislaufwirtschaft um jeden Preis \u00fcberall einzuf\u00fchren.<\/p>\n<p>F\u00fcr diesen ersten Schritt sind keine besonderen Fachkenntnisse erforderlich. Die Verantwortlichen k\u00f6nnen ganz einfach alle Beteiligten (Lieferanten, Partner, Mitarbeiter usw.) zusammenbringen. Es geht darum, Informationen zu sammeln und die kollektive Intelligenz zu mobilisieren, um L\u00f6sungen zu finden.<\/p>\n<h2>2. Die Kreislaufwirtschaft schrittweise im Unternehmen einf\u00fchren<\/h2>\n<p>Mithilfe einer solchen Kartierung erhalten die Unternehmen einen klaren \u00dcberblick \u00fcber die verschiedenen M\u00f6glichkeiten f\u00fcr einen Einsatz der Kreislaufwirtschaft. Ausgehend von den beobachteten makro\u00f6konomischen Problemen k\u00f6nnen sie L\u00f6sungen auf mikro\u00f6konomischer Ebene entwickeln. Es gibt unz\u00e4hlige M\u00f6glichkeiten. Unternehmen, die die Kreislaufwirtschaft in ihre Gesch\u00e4ftsstrategie integrieren wollen, k\u00f6nnen zum Beispiel:<\/p>\n<ul>\n<li>die anfallenden Abf\u00e4lle verringern;<\/li>\n<li>industriellen und regionalen umweltfreundlichen Verfahren den Vorzug geben;<\/li>\n<li>den Lebenszyklus ihrer Produkte \u00fcberdenken;<\/li>\n<li>mehr \u00f6kologisch gestaltete Waren produzieren;<\/li>\n<li>sich f\u00fcr ein neues, auf Funktionalit\u00e4t basierendes Wirtschaftsmodell entscheiden<\/li>\n<li>usw.<\/li>\n<\/ul>\n<p>Die Unternehmen sind dann in der Lage, einen Kreislaufwirtschaftsprozess zu entfalten oder sogar ihre eigene Kreislaufwirtschaftsstrategie zu entwickeln. In beiden F\u00e4llen muss diese Initiative nahtlos in die Unternehmensstrategie integriert werden. Denn sie wird nicht funktionieren, wenn sie sich am Rande der Gesamtdynamik bewegt und von einer speziellen Person oder einem Team geleitet wird.<\/p>\n<p>Die digitale Transformation ist daf\u00fcr ein perfektes Beispiel. Die Digitalisierung muss, ebenso wie die Kreislaufwirtschaft, von allen umgesetzt werden. Diese Transformationen m\u00fcssen alle Ebenen und alle Abteilungen funktions\u00fcbergreifend durchdringen. Da diese gro\u00df angelegten Projekte das gesamte Unternehmen betreffen, erfordern sie auch ein komplexes Change Management.<\/p>\n<p>Justine Laurent r\u00e4t au\u00dferdem dazu, schrittweise vorzugehen: \u201eDa man irgendwo beginnen muss, liegt es im Interesse des Unternehmens, die Kreislaufwirtschaft zun\u00e4chst in einem Bereich mit hohem Potenzial (Wachstumsmarkt, reifer Markt usw.) auszuprobieren. Dieser erste Test erm\u00f6glicht es ihnen in der Regel, zu lernen und diesen Paradigmenwechsel im Unternehmen zu verankern.\u201c<\/p>\n<h2>3. Auf die verschiedenen Erfolgsfaktoren setzen<\/h2>\n<p>Es gibt vier bew\u00e4hrte Verfahren f\u00fcr eine erfolgreiche Integration der Kreislaufwirtschaft im Unternehmen.<\/p>\n<h3>3.1 Ein abgestimmtes Unternehmensleitbild haben<\/h3>\n<p>Zun\u00e4chst einmal ist es von entscheidender Bedeutung, dass die Mission, d.h. die Existenzberechtigung des Unternehmens, aber auch die CSR-Strategie mit den Grunds\u00e4tzen der Kreislaufwirtschaft \u00fcbereinstimmen. Dadurch erh\u00e4lt eine solche strategische Wende Sinn, w\u00e4hrend sie gleichzeitig auf nat\u00fcrliche Weise in die Roadmaps der einzelnen Abteilungen einflie\u00dft.<\/p>\n<h3>3.2 Alle notwendigen Akteure zusammenbringen<\/h3>\n<p>Alle internen und externen Stakeholder, die von dem Problem betroffen sind, m\u00fcssen an einen Tisch gebracht werden. Dazu geh\u00f6ren Betrieb, Support, Einkauf, Partner, Lieferanten, Management&#8230; Man darf dabei jedoch nicht vergessen, dass L\u00f6sungen nie innerhalb bestehender Strukturen gefunden werden. Daher ist es wichtig, eine m\u00f6glichst breite Sichtweise zu haben. Dies f\u00fchrt auch zu ganzheitlichen L\u00f6sungen, die alle Dimensionen des jeweiligen Projekts abdecken.<\/p>\n<h3>3.3 Teams fr\u00fchzeitig mobilisieren<\/h3>\n<p>Es ist wichtig, die Mitarbeiter so fr\u00fch wie m\u00f6glich einzubeziehen, und zwar bereits in der Vordiagnosephase, damit sie sich den \u00dcbergang zur Kreislaufwirtschaft zu eigen machen und ihn bestm\u00f6glich mitgestalten. Dazu k\u00f6nnen auch Schulungen geh\u00f6ren, welche sicherstellen, dass jeder \u00fcber ein genaues Verst\u00e4ndnis der Herausforderungen verf\u00fcgt, die eine solche Transformation mit sich bringt.<\/p>\n<h3>3.4 Die richtigen Indikatoren festlegen<\/h3>\n<p>Damit dies funktioniert, m\u00fcssen die Ziele, die Messinstrumente und die Key Performance Indicators (KPIs) mit dem Ansatz \u00fcbereinstimmen. Bestehende Indikatoren (Umwelt- und Ressourcenverbrauchsindikatoren) m\u00fcssen m\u00f6glicherweise angepasst werden, aber auch neue, eher qualitative Indikatoren m\u00fcssen aufgenommen werden. Dies erm\u00f6glicht sowohl die Messung der Auswirkungen der durchgef\u00fchrten Ma\u00dfnahmen als auch eine umfassendere Steuerung der Strategie der Kreislaufwirtschaft.<\/p>\n<p>Die Kreislaufwirtschaft ist nicht nur eine Antwort auf die Herausforderungen des \u00f6kologischen und solidarischen Wandels, sondern auch ein gewaltiger Transformationshebel, der die Unternehmen wettbewerbsf\u00e4higer und widerstandsf\u00e4higer macht. Sie m\u00fcssen diesen Prozess Schritt f\u00fcr Schritt, gemeinsam und mit einem systemischen Ansatz umsetzen, um eine echte Kreislaufwirtschaft zu schaffen.<\/p>\n<p>Wollen Sie mehr erfahren? Dann laden Sie unser <a href=\"https:\/\/www.manutan.de\/blog\/nachhaltiger-arbeitsplatz\/beschaffung-und-csr-politik\/\">Whitepaper \u201eEinkaufspolitik und CSR\u201c<\/a> herunter!<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um den weltweiten Herausforderungen der nachhaltigen Entwicklung und des Umweltschutzes gerecht zu werden, entwerfen die Unternehmen ihre CSR-Strategie (Corporate Social Responsibility) und priorisieren diese sogar. Einer der wichtigsten Hebel f\u00fcr ein solches Vorgehen ist das wachsende Interesse an der Kreislaufwirtschaft. Und das aus gutem Grund, denn die NRO Circle Economy behauptet, dass ein Fokus auf die Kreislaufwirtschaft die Treibhausgasemissionen um&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":73684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-72355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachhaltiger-arbeitsplatz"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72355"}],"version-history":[{"count":3,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72355\/revisions"}],"predecessor-version":[{"id":74128,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72355\/revisions\/74128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/73684"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}