{"id":72384,"date":"2023-08-16T10:00:02","date_gmt":"2023-08-16T10:00:02","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72214"},"modified":"2026-01-23T20:34:02","modified_gmt":"2026-01-23T20:34:02","slug":"wie-berechnen-und-optimieren-sie-die-kosten-fuer-ihr-beschaffungsmanagement","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/wie-berechnen-und-optimieren-sie-die-kosten-fuer-ihr-beschaffungsmanagement\/","title":{"rendered":"Wie berechnen und optimieren Sie die Kosten f\u00fcr Ihr Beschaffungsmanagement?"},"content":{"rendered":"<figure class=\"post-hero\">\n        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/01\/Wie_berechnen_und_optimieren_Sie_die_Kosten_f__r_Ihr_Beschaffungsmanagement.jpg\" alt=\"\" \/><br \/>\n      <\/figure>\n<div class=\"post-content\">\n<p>Das Management der Lieferkette ist in Unternehmen hochgradig strategisch. Dies wirft nicht nur wirtschaftliche Fragen auf, sondern betrifft auch Aspekte, wie die  Kundenzufriedenheit und das Markenimage. Mit einem effektiven Beschaffungsmanagement erf\u00fcllen Sie jederzeit die Nachfrage der Kunden und f\u00f6rdern gleichzeitig die Rentabilit\u00e4t und Nachhaltigkeit des Unternehmens. Deshalb ist es wichtig, dass sich die Einkaufs- und Logistikabteilungen darauf konzentrieren, die Kosten f\u00fcr das Beschaffungsmanagement zu berechnen und dann zu optimieren.<\/p>\n<h2>Beschaffungsmanagement: eine strategische Herausforderung<\/h2>\n<p>Wenn in einem Unternehmen von Beschaffung die Rede ist, bezieht sich dies auf den Einkauf von Waren f\u00fcr unterschiedliche Zwecke. Es kann sich dabei um Produkte handeln, die direkt f\u00fcr den Weiterverkauf bestimmt sind, um Materialien, die f\u00fcr die Herstellung von Endprodukten oder f\u00fcr Dienstleistungen ben\u00f6tigt werden, oder aber um Waren, die gelagert werden sollen.<\/p>\n<p>Wie Graham Stevens, seinerzeit Senior Consultant bei der Beratungs- und Wirtschaftspr\u00fcfungsgesellschaft Peat Marwick McLintock (inzwischen umbenannt in KPMG), in seinem Artikel \u201e<i>Integrating the Supply Chain<\/i>\u201c betonte:  <i>\u201eDas Ziel des Lieferkettenmanagements ist es, <\/i><i><b>die Kundenanforderungen mit dem Materialfluss <\/b><\/i>von <i>den Zulieferern <\/i>zu <b><i>synchronisieren<\/i><\/b><i>, um ein Gleichgewicht zwischen dem herzustellen, was oft als widerspr\u00fcchliche Ziele angesehen wird, n\u00e4mlich hoher Kundenservice, geringe Lagerhaltung und niedrige St\u00fcckkosten.<\/i>\u201cDieser Text wurde 1989 ver\u00f6ffentlicht und gilt noch heute als Referenz f\u00fcr die gegenw\u00e4rtigen Einkaufs- und Logistikabteilungen.<\/p>\n<p>Beim Lieferkettenmanagement geht es also darum, die verschiedenen logistischen Abl\u00e4ufe zu synchronisieren und die Ressourcen zu optimieren, und zwar auf m\u00f6glichst effiziente Weise. In dieser Funktion umfasst das Beschaffungsmanagement <b>f\u00fcnf Hauptkomponenten: <\/b><\/p>\n<ol>\n<li>\n<p>Planung und Verwaltung der von den Kunden gestellten Anfragen<\/p>\n<\/li>\n<li>\n<p><i>Sourcing<\/i>, d.h. die Auswahl von Lieferanten und Dienstleistern, die alle Waren, Serviceleistungen und Leistungen umfasst, die ein Unternehmen kaufen kann<\/p>\n<\/li>\n<li>\n<p>Herstellung, d.h. die Annahme von Materialien und\/oder G\u00fctern, die zur Herstellung der Endprodukte ben\u00f6tigt werden<\/p>\n<\/li>\n<li>\n<p>Lieferung und Logistik, welche die Koordination der Bestellungen und anschlie\u00dfend die Planung der Lieferungen abdecken<\/p>\n<\/li>\n<li>\n<p>Die Retouren, d.h. die R\u00fccknahme von Produkten, die von Kunden aus verschiedenen Gr\u00fcnden zur\u00fcckgeschickt wurden, durch das Unternehmen.<\/p>\n<\/li>\n<\/ol>\n<h2>Wie berechnen Sie die Kosten f\u00fcr das Beschaffungsmanagement?<\/h2>\n<p>Um die Kosten des Beschaffungsmanagements zu berechnen, m\u00fcssen Unternehmen drei Schl\u00fcsselelemente ber\u00fccksichtigen, unabh\u00e4ngig davon, ob es sich um variable Kosten oder Anlagekosten handelt: die Kosten f\u00fcr die Auftragserteilung, die Kosten f\u00fcr den Besitz des Lagerbestands und die Kosten f\u00fcr eventuelle Engp\u00e4sse.<\/p>\n<h3>Die Kosten der Auftragserteilung<\/h3>\n<p>Dieser Indikator umfasst alle Aufwendungen f\u00fcr die Auftragserteilung, d.h.: <\/p>\n<ul>\n<li>\n<p>administrative und logistische Betreuung<\/p>\n<\/li>\n<li>\n<p>Transport<\/p>\n<\/li>\n<li>\n<p>Empfang und Bef\u00f6rderung<\/p>\n<\/li>\n<li>\n<p>Computerausr\u00fcstung und Software<\/p>\n<\/li>\n<li>\n<p>Belastung der am Prozess beteiligten Mitarbeiter<\/p>\n<\/li>\n<li>\n<p>usw. <\/p>\n<\/li>\n<\/ul>\n<h3>Die Kosten f\u00fcr den Besitz des Lagerbestandes<\/h3>\n<p>Dieser Punkt deckt alle Kosten ab, die mit der Lagerhaltung verbunden sind, sowohl direkte als auch indirekte, einschlie\u00dflich:<\/p>\n<ul>\n<li>\n<p>Versicherungen<\/p>\n<\/li>\n<li>\n<p>\u00dcberwachung und Schutz<\/p>\n<\/li>\n<li>\n<p>Anmietung und Instandhaltung von R\u00e4umlichkeiten<\/p>\n<\/li>\n<li>\n<p>Abschreibung der Einrichtungen<\/p>\n<\/li>\n<li>\n<p>Verwaltungskosten<\/p>\n<\/li>\n<li>\n<p>Heizung<\/p>\n<\/li>\n<li>\n<p>Material<\/p>\n<\/li>\n<li>\n<p>usw.<\/p>\n<\/li>\n<\/ul>\n<h3>Die Kosten f\u00fcr Engp\u00e4sse<\/h3>\n<p>Zu den vorgenannten Kosten kommen nat\u00fcrlich noch die Kosten f\u00fcr m\u00f6gliche Fehlbest\u00e4nde hinzu, wenn es zu Lieferverz\u00f6gerungen oder Fehlern bei den Lieferprognosen kommt. Diese Kosten k\u00f6nnen den Verlust von Auftr\u00e4gen, den Einsatz von Subunternehmern, nicht besch\u00e4ftigte Arbeitskr\u00e4fte usw. nach sich ziehen.<\/p>\n<p>Wenn man die Kosten f\u00fcr die Auftragserteilung, die Kosten f\u00fcr den Besitz von Lagerbest\u00e4nden und die Kosten f\u00fcr Engp\u00e4sse \u00fcber ein Jahr addiert, erh\u00e4lt das Unternehmen die j\u00e4hrlichen Kosten f\u00fcr das Beschaffungsmanagement. Es ist daher von entscheidender Bedeutung, diese Prozesse vollst\u00e4ndig zu beherrschen, um sie anschlie\u00dfend optimieren zu k\u00f6nnen.<\/p>\n<h2>Wie optimieren Sie die Kosten f\u00fcr das Beschaffungsmanagement?<\/h2>\n<p>Nachdem sie eine solche Berechnung durchgef\u00fchrt haben, k\u00f6nnen Unternehmen die Komponenten ihres Beschaffungsmanagements optimieren, sowohl in Bezug auf die Lager- als auch auf die Auftragsverwaltung. Die Logistikabteilungen k\u00f6nnen sich auf bew\u00e4hrte Vorgehensweisen und technologische Hilfsmittel st\u00fctzen, um die Lagerverwaltung zu optimieren. <\/p>\n<h3>Die Voraussetzungen schaffen<\/h3>\n<p>Zuallererst m\u00fcssen Unternehmen das <b>optimale Modell f\u00fcr das Beschaffungsmanagement<\/b> (Prognosemethode, Kanban-Methode, Just-in-Time-Methode, Kalender-Methode usw.) sowie die erforderlichen Computersysteme und Software ausw\u00e4hlen.<\/p>\n<p>Sobald sie diese Punkte gekl\u00e4rt haben, k\u00f6nnen sie mehrere Hebel zur Optimierung der Lagerverwaltung aktivieren:<\/p>\n<ul>\n<li>\n<p>Zu hohe Lagerbest\u00e4nde vermeiden<\/p>\n<\/li>\n<li>\n<p>Fehlbest\u00e4nde antizipieren<\/p>\n<\/li>\n<li>\n<p>Lagerkapazit\u00e4ten optimieren<\/p>\n<\/li>\n<li>\n<p>Ruhende Best\u00e4nde reduzieren<\/p>\n<\/li>\n<li>\n<p>usw.<\/p>\n<\/li>\n<\/ul>\n<p>Der Einkauf beinflusst ma\u00dfgeblich die Kosten der Auftragserteilung.  In diesem Bereich gibt es zwei Haupthebel zur Optimierung, die auf die Gesamtkosten der Beschaffung fokussiert sind: die Rationalisierung des Lieferantenportfolios und die Digitalisierung der Transaktionen.<\/p>\n<h3>Rationalisierung des Lieferantenportfolios<\/h3>\n<p><a href=\"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/langfristige-ausgaben-rationalisieren-sie-ihr-lieferantenportfolio\/\">Eink\u00e4ufer k\u00f6nnen damit beginnen, ihr Lieferantenportfolio zu rationalisieren<\/a>. Dies f\u00fchrt zu doppelten Einsparungen, sowohl bei den <b>Kosten f\u00fcr das Lieferantenmanagement als auch bei den Kosten f\u00fcr die Auftragserteilung<\/b>. <\/p>\n<p>Diese Rationalisierung tr\u00e4gt au\u00dferdem dazu bei, die Anzahl der Bestellungen, aber auch die Anzahl der Lieferungen und die damit verbundenen Treibhausgasemissionen zu reduzieren. <\/p>\n<p>Schlie\u00dflich f\u00fchrt ein solches Vorgehen de facto zur Entwicklung strategischer Partnerschaften mit den wichtigsten Lieferanten oder H\u00e4ndlern.<\/p>\n<h3>Transaktionen digitalisieren<\/h3>\n<p>Auch Eink\u00e4ufer haben ein Interesse daran, <a href=\"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/long-tail-ausgaben-digitalisieren-sie-ihre-transaktionen\/\">den Procure-to-Pay-Prozess ihres Unternehmens zu digitalisieren<\/a> (vom Zugriff auf die Produkte \u00fcber die Bestellung bis hin zur Bezahlung). Neben der Senkung der <b>Verwaltungskosten<\/b> bietet dieser Hebel noch viele weitere Vorteile. Denn es wird nicht nur der Transaktionsprozess beschleunigt, sondern auch die Anzahl der Fehler reduziert und die Umweltbelastung des Unternehmens verringert.<\/p>\n<p>Wie Sie sehen, erm\u00f6glicht die Berechnung der Kosten des Beschaffungsmanagements die Identifizierung und Aktivierung geeigneter Optimierungshebel, sowohl bei der Logistik als auch beim Einkauf. Dies ist eine wesentliche \u00dcberlegung, wenn Sie auf eine enge Zusammenarbeit zwischen den Abteilungen und der digitalen Transformation des Unternehmens setzen. Denn das Beschaffungsmanagement ist nach wie vor eine Frage der <b>Rentabilit\u00e4t und der Wertsch\u00f6pfung<\/b> und damit <b>des Fortbestands eines Unternehmens<\/b>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Management der Lieferkette ist in Unternehmen hochgradig strategisch. Dies wirft nicht nur wirtschaftliche Fragen auf, sondern betrifft auch Aspekte, wie die Kundenzufriedenheit und das Markenimage. Mit einem effektiven Beschaffungsmanagement erf\u00fcllen Sie jederzeit die Nachfrage der Kunden und f\u00f6rdern gleichzeitig die Rentabilit\u00e4t und Nachhaltigkeit des Unternehmens. Deshalb ist es wichtig, dass sich die Einkaufs- und Logistikabteilungen darauf konzentrieren, die Kosten&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":57205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-72384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intelligentes-und-effizientes-arbeiten"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72384"}],"version-history":[{"count":1,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72384\/revisions"}],"predecessor-version":[{"id":73033,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72384\/revisions\/73033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/57205"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}