{"id":72393,"date":"2023-09-29T09:30:02","date_gmt":"2023-09-29T09:30:02","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72221"},"modified":"2026-02-12T11:42:00","modified_gmt":"2026-02-12T11:42:00","slug":"kuenstliche-intelligenz-im-unternehmen-auf-dem-weg-zu-einer-besseren","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/kuenstliche-intelligenz-im-unternehmen-auf-dem-weg-zu-einer-besseren\/","title":{"rendered":"K\u00fcnstliche Intelligenz im Unternehmen: auf dem Weg zu einer besseren Performance Ihres Beschaffungswesens"},"content":{"rendered":"<figure class=\"post-hero\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-73632 size-full\" src=\"\/wp-content\/uploads\/2023\/09\/K__nstliche_Intelligenz_im_Unternehmen_auf_dem_Weg_zu_einer_besseren_Performance_Ihres_Beschaffungswesens-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1338\" srcset=\"\/wp-content\/uploads\/2023\/09\/K__nstliche_Intelligenz_im_Unternehmen_auf_dem_Weg_zu_einer_besseren_Performance_Ihres_Beschaffungswesens-scaled.jpg 2560w, \/wp-content\/uploads\/2023\/09\/K__nstliche_Intelligenz_im_Unternehmen_auf_dem_Weg_zu_einer_besseren_Performance_Ihres_Beschaffungswesens-300x157.jpg 300w, \/wp-content\/uploads\/2023\/09\/K__nstliche_Intelligenz_im_Unternehmen_auf_dem_Weg_zu_einer_besseren_Performance_Ihres_Beschaffungswesens-1024x535.jpg 1024w, \/wp-content\/uploads\/2023\/09\/K__nstliche_Intelligenz_im_Unternehmen_auf_dem_Weg_zu_einer_besseren_Performance_Ihres_Beschaffungswesens-768x401.jpg 768w, \/wp-content\/uploads\/2023\/09\/K__nstliche_Intelligenz_im_Unternehmen_auf_dem_Weg_zu_einer_besseren_Performance_Ihres_Beschaffungswesens-1536x803.jpg 1536w, \/wp-content\/uploads\/2023\/09\/K__nstliche_Intelligenz_im_Unternehmen_auf_dem_Weg_zu_einer_besseren_Performance_Ihres_Beschaffungswesens-2048x1070.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<div class=\"post-content\">\n<p>Seit einigen Monaten r\u00fcckt die K\u00fcnstliche Intelligenz (KI) mit der Entwicklung der generativen KI (GPT-4, ChatGPT, Einstein GPT, DALL-E usw.) immer mehr ins Rampenlicht. K\u00fcnstliche Intelligenz ist ein enormer Performance-Hebel und bereits Realit\u00e4t in zahlreichen Branchen und Berufen (Gesundheit, Versicherung, Finanzwesen, Handel usw.). Diese neue Technologie verspricht jedoch noch ein enormes Entwicklungspotenzial. Laut einem von Accenture ver\u00f6ffentlichten Bericht k\u00f6nnte KI die Rentabilit\u00e4t von Unternehmen bis 2035 um ca. 38% steigern. Im Beschaffungswesen zeichnen sich bereits erste Anwendungsf\u00e4lle ab und die Einsatzm\u00f6glichkeiten werden konkreter. Von der Datenverarbeitung bis zur Prozessverbesserung: Erfahren Sie, wozu K\u00fcnstliche Intelligenz f\u00e4hig ist.<\/p>\n<h2>Wie funktioniert K\u00fcnstliche Intelligenz im Unternehmen?<\/h2>\n<p>Hinter K\u00fcnstlicher Intelligenz verbirgt sich eine Reihe von <b>Technologien, die \u201eintelligent\u201c und selbstst\u00e4ndig arbeiten <\/b><i>(Machine Learning<\/i>, <i>Deep Learning<\/i> usw.). Konkret bedeutet das, dass diese Tools Aufgaben erledigen k\u00f6nnen, die \u00e4hnliche kognitive F\u00e4higkeiten zur Verarbeitung von Informationen erfordern wie die des Menschen. Diese Maschinen k\u00f6nnen daher bestimmte Verhaltensweisen wie Wahrnehmung, Denken, Planen, Lernen usw. reproduzieren.<\/p>\n<p>KI <b>sammelt also <\/b>in Verbindung mit <i>Big Data<\/i> <b>riesige Datenmengen<\/b>, um sie zu untersuchen und daraus Modelle und Korrelationen abzuleiten. Innerhalb der Einkaufsfunktion kann es sich dabei um die Gesamtheit der Daten aus verschiedenen Quellen handeln: Einkaufsplattform, Online-Kataloge, Software zum Lieferantenmanagement (<i>Supplier Relationship Management<\/i>), ERP-Systeme (<i>Enterprise Ressource Planning<\/i>) usw.<\/p>\n<p>Die KI besteht aus einer Reihe von Algorithmen <b>und ist in der Lage, diese Daten zu verarbeiten und auszuwerten<\/b>, sie zu konsolidieren, automatisch zu duplizieren und in Echtzeit zu indizieren. Die auf dieser Technologie basierenden Tools erm\u00f6glichen es den K\u00e4ufern somit, diese Informationen kontinuierlich und in jeder Phase des Kaufprozesses zu verfolgen und zu nutzen. Dies betrifft sowohl die Identifizierung von Lieferanten als auch die Erstellung von Vertr\u00e4gen, die Erfassung und Planung von Bestellungen, die \u00dcberwachung des Wareneingangs und der Rechnungsstellung usw.<\/p>\n<p>Die Auswirkungen der K\u00fcnstlichen Intelligenz auf Unternehmen und insbesondere auf die Einkaufsfunktion d\u00fcrften demzufolge von entscheidender Bedeutung sein. Eine aktuelle US-Studie, die gemeinsam von Forschern von OpenAI, Open Research und der University of Pennsylvania durchgef\u00fchrt wurde, betont, dass etwa 80% der Arbeitnehmer bei <i>mindestens<\/i> 10% ihrer Aufgaben vom Vormarsch generativer KI-Systeme betroffen sein d\u00fcrften. Bei 19% der Besch\u00e4ftigten w\u00e4ren sogar 50% der Aufgaben betroffen. Angesichts dieser sich stark entwickelnden Technologie ist Bill Gates, Mitbegr\u00fcnder von Microsoft, davon \u00fcberzeugt, <i>\u201edass es sich dabei um den <\/i><i><b>gr\u00f6\u00dften technologischen Fortschritt<\/b><\/i><i> seit der Entwicklung der grafischen Benutzeroberfl\u00e4che handelt\u201c<\/i>.<\/p>\n<h2>KI will Beschaffungsprozesse optimieren<\/h2>\n<p>Durch die Verarbeitung und Analyse von Daten generieren Unternehmen Mehrwert w\u00e4hrend des gesamten Beschaffungsprozesses. Heute befinden sich diese Technologien bereits in der Phase der Aneignung und es ergeben sich erste Anwendungsf\u00e4lle.<\/p>\n<h3>Die Beschaffungskategorien<\/h3>\n<p>K\u00fcnstliche Intelligenz kann <b>die Beschaffung strukturieren<\/b>, indem sie einem definierten Prozess folgt, der einer bestimmten Nomenklatur und Typologie entspricht. Wenn beispielsweise ein interner Kunde einen Bedarf anmeldet, kann das Tool feststellen, ob dieser Bedarf durch einen Katalog oder einen Lieferantenvertrag abgedeckt ist, ob ein Angebot von einem bereits in der Datenbank enthaltenen Lieferanten eingeholt oder ein Lieferanten-<i>Sourcing<\/i> durchgef\u00fchrt werden sollte.<\/p>\n<h3>Die Rechnungslegung<\/h3>\n<p>Innerhalb der Beschaffungsabteilung konzentriert sich der erste Anwendungsbereich von KI oft auf den <i>Procure-to-Pay-<\/i>Prozess und insbesondere auf die Rechnungslegung. Dies mag daran liegen, dass es sich um sehr zeitaufw\u00e4ndige Prozesse handelt, die keinen Mehrwert bieten. Heute sind beispielsweise einige Rechnungsmanagementmodule in der Lage, <b>die Verarbeitung von nahezu der H\u00e4lfte der Rechnungen zu automatisieren<\/b>. Das Tool extrahiert die relevanten Informationen, gleicht sie mit der Bestellung ab und l\u00f6st die Zahlung aus &#8211; ganz ohne menschliches Zutun.<\/p>\n<h3>Das <i>Sourcing<\/i> von Lieferanten<\/h3>\n<p>Im Vorfeld von Ausschreibungen kann die KI den Markt erkunden und <b>Anbieter vorqualifizieren<\/b>. Einige L\u00f6sungen sind dazu bereits in der Lage und k\u00f6nnen sogar kleinste, hochspezialisierte Unternehmen ermitteln, die den Bedarf perfekt erf\u00fcllen. Ein weiteres Beispiel: Ein <i>Bot<\/i> kann auch die Antworten von Lieferanten im Rahmen einer Informationsanfrage (<i>Request For Information, <\/i>RFI) analysieren und Empfehlungen vorschlagen.<\/p>\n<h3>Die Vertr\u00e4ge<\/h3>\n<p>KI kann auch <b>die Vertragscompliance gew\u00e4hrleisten.<\/b> Dies wurde \u00fcbrigens von einer Bankengruppe getestet, die ihre Vertragsreferenzdatenbank anl\u00e4sslich der DSGVO (Datenschutz-Grundverordnung) analysieren musste. Das Unternehmen setzte KI ein, um alle Vertr\u00e4ge zu ermitteln, die personenbezogene Daten enthielten, und sicherzustellen, dass die erforderlichen Klauseln enthalten waren. Das Einkaufsteam sch\u00e4tzt, dass sich die Bearbeitungszeit um den Faktor 6 verringert hat!<\/p>\n<h3>Die Lieferantenbeziehung<\/h3>\n<p>KI kann auch viele Facetten der Lieferantenbeziehung \u00fcbernehmen, insbesondere das <b>Risiko- und Zwischenfallmanagement<\/b>. Beispielsweise kann die Technologie durch einfachen Abgleich der vertraglichen Informationen Vers\u00e4umnisse oder Nichteinhaltungen von Verpflichtungen melden. Wenn also ein Lieferant die vereinbarten Liefertermine nicht einh\u00e4lt, kann die KI den betreffenden Eink\u00e4ufer warnen und ihm Alternativen vorschlagen, um eine Beeintr\u00e4chtigung der Produktion zu vermeiden.<\/p>\n<h3>Die Steuerung der Leistung<\/h3>\n<p>K\u00fcnstliche Intelligenz kann schlie\u00dflich den Eink\u00e4ufer bei der Steuerung der Einkaufsleistung unterst\u00fctzen. Denn sie hilft ihm, den \u00dcberblick \u00fcber seine Ausgaben zu behalten, zuk\u00fcnftige Kosten zu antizipieren etc. So kann er proaktiv anstatt reaktiv handeln.<\/p>\n<p>Die KI <b>beschleunigt auch die Entscheidungsfindung,<\/b> indem sie aussagekr\u00e4ftige Analysen auf der Grundlage von Echtzeitdaten liefert. So ist der K\u00e4ufer in der Lage, schneller fundierte Entscheidungen zu treffen. Au\u00dferdem kann er Risiken antizipieren und die notwendigen Ma\u00dfnahmen ergreifen, um die Gesch\u00e4ftst\u00e4tigkeit des Unternehmens aufrechtzuerhalten.<\/p>\n<p>Die KI verspricht zahlreiche Vorteile f\u00fcr die Beschaffungsabteilungen: mehr Informationen, mehr Produktivit\u00e4t, mehr Einsparungen, mehr Sicherheit\u00a0&#8230; Dank der digitalen Transformation und der Nutzung neuer Technologien (darunter KI) k\u00f6nnen sich Eink\u00e4ufer langfristig auf Aufgaben mit h\u00f6herem Mehrwert konzentrieren, wie z.B. die Entwicklung der Lieferantenbeziehungen oder der Beitrag zur CSR (Corporate Social Responsibility). K\u00fcnstliche Intelligenz ist <b>Antriebskraft f\u00fcr Wettbewerbsf\u00e4higkeit, Innovation und Wertsch\u00f6pfung,<\/b> stellt die Unternehmen jedoch vor gro\u00dfe Herausforderungen.<\/p>\n<p>Lesen Sie unser <a href=\"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/langfristige-ausgaben-einfuehrung-einer-schlanken-beschaffung\/\">Whitepaper \u201eLong Tail Spend: F\u00fchren Sie Lean Procurement ein\u201c<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seit einigen Monaten r\u00fcckt die K\u00fcnstliche Intelligenz (KI) mit der Entwicklung der generativen KI (GPT-4, ChatGPT, Einstein GPT, DALL-E usw.) immer mehr ins Rampenlicht. K\u00fcnstliche Intelligenz ist ein enormer Performance-Hebel und bereits Realit\u00e4t in zahlreichen Branchen und Berufen (Gesundheit, Versicherung, Finanzwesen, Handel usw.). Diese neue Technologie verspricht jedoch noch ein enormes Entwicklungspotenzial. Laut einem von Accenture ver\u00f6ffentlichten Bericht k\u00f6nnte KI&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":73632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-72393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intelligentes-und-effizientes-arbeiten"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72393"}],"version-history":[{"count":3,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72393\/revisions"}],"predecessor-version":[{"id":74133,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72393\/revisions\/74133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/73632"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}