{"id":72406,"date":"2023-10-10T08:00:02","date_gmt":"2023-10-10T08:00:02","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72230"},"modified":"2026-02-12T11:36:28","modified_gmt":"2026-02-12T11:36:28","slug":"wie-koennen-sie-das-pareto-prinzip-anwenden-um-ihre-beschaffungsstrategie-zu","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/wie-koennen-sie-das-pareto-prinzip-anwenden-um-ihre-beschaffungsstrategie-zu\/","title":{"rendered":"Wie k\u00f6nnen Sie das Pareto-Prinzip anwenden, um Ihre Beschaffungsstrategie zu optimieren?"},"content":{"rendered":"<figure class=\"post-hero\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-73628 size-full\" src=\"\/wp-content\/uploads\/2023\/10\/Wie_k_nnen_Sie_das_Pareto-Prinzip_anwenden__um_Ihre_Beschaffungsstrategie_zu_optimieren_copy-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1338\" srcset=\"\/wp-content\/uploads\/2023\/10\/Wie_k_nnen_Sie_das_Pareto-Prinzip_anwenden__um_Ihre_Beschaffungsstrategie_zu_optimieren_copy-scaled.jpg 2560w, \/wp-content\/uploads\/2023\/10\/Wie_k_nnen_Sie_das_Pareto-Prinzip_anwenden__um_Ihre_Beschaffungsstrategie_zu_optimieren_copy-300x157.jpg 300w, \/wp-content\/uploads\/2023\/10\/Wie_k_nnen_Sie_das_Pareto-Prinzip_anwenden__um_Ihre_Beschaffungsstrategie_zu_optimieren_copy-1024x535.jpg 1024w, \/wp-content\/uploads\/2023\/10\/Wie_k_nnen_Sie_das_Pareto-Prinzip_anwenden__um_Ihre_Beschaffungsstrategie_zu_optimieren_copy-768x401.jpg 768w, \/wp-content\/uploads\/2023\/10\/Wie_k_nnen_Sie_das_Pareto-Prinzip_anwenden__um_Ihre_Beschaffungsstrategie_zu_optimieren_copy-1536x803.jpg 1536w, \/wp-content\/uploads\/2023\/10\/Wie_k_nnen_Sie_das_Pareto-Prinzip_anwenden__um_Ihre_Beschaffungsstrategie_zu_optimieren_copy-2048x1070.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<div class=\"post-content\">\n<p>Das Pareto-Prinzip, auch als 20-80-Regel bekannt, bezieht sich auf eine statistische Regelm\u00e4\u00dfigkeit, die in zahlreichen Bereichen beobachtet wird. Danach werden 80% des Gesamtwerts durch 20% der wichtigsten Posten erzielt. Die Beschaffungsfunktion hat sich dieses Prinzip zu eigen gemacht, um ihre Eink\u00e4ufe nach drei Kategorien (A, B und C) zu ordnen und die damit verbundene Strategie zu optimieren. Dennoch sollte man sich nicht ausschlie\u00dflich darauf verlassen und auch andere Parameter ber\u00fccksichtigen.<\/p>\n<h2>Urspr\u00fcnge und Definition des Pareto-Prinzips<\/h2>\n<p>Im 19. Jahrhundert f\u00fchrte der italienische \u00d6konom und Soziologe Vilfredo Pareto eine statistische Studie \u00fcber die Verm\u00f6gensverteilung in Italien durch. Dabei stellte er fest, dass sich im Durchschnitt<b> 80% des Verm\u00f6gens eines Landes im Besitz von 20% der Bev\u00f6lkerung befanden.<\/b> Fasziniert von dieser Beobachtung, wandelte er dieses Gesetz der Einkommensverteilung anschlie\u00dfend in eine mathematische Formel um.<\/p>\n<p>Einige Jahrzehnte sp\u00e4ter pr\u00e4gte Joseph M. Juran den Begriff \u201ePareto-Prinzip\u201c, um zu verdeutlichen, dass etwa 80% des Gesamtwerts durch 20% der wichtigsten Posten erzielt werden. Es stellte sich heraus, dass diese statistische Regelm\u00e4\u00dfigkeit in verschiedenen Bereichen zu beobachten ist, unter anderem auch im Unternehmen.<\/p>\n<p>Es wird beispielsweise angenommen, dass:<\/p>\n<ul>\n<li>80% des Umsatzes eines Unternehmens von 20% seiner Kunden erwirtschaftet werden;<\/li>\n<li>80% der Steuereinnahmen von 20% der Steuerpflichtigen stammen;<\/li>\n<li>80% der Lagerfl\u00e4che von 20% der Produkte belegt werden;<\/li>\n<li>80% der Reklamationen von 20% der Kunden ausgehen.<\/li>\n<\/ul>\n<p>Dieses Instrument verdeutlicht also, wie wichtig es ist, seine Ressourcen zu optimieren, um den h\u00f6chsten Ertrag zu erzielen. Mit anderen Worten: Wir m\u00fcssen uns auf die 20% konzentrieren, um 80% der Ergebnisse zu erzielen. Im Beschaffungswesen f\u00fchrt dies zu \u00dcberlegungen, wie man die Einkaufskategorien und die damit verbundenen Kosten optimieren kann.<\/p>\n<h2>Eink\u00e4ufe der Klasse A, B und C<\/h2>\n<p>Die Beschaffungsfunktion verwendet eine auf dem Pareto-Prinzip basierende Klassifizierungsmethode, um ihre Eink\u00e4ufe zu priorisieren, die sogenannte \u201eABC-Methode\u201c.<\/p>\n<p>Es gibt drei verschiedene Kategorien:<\/p>\n<ol>\n<li><b>Eink\u00e4ufe der Kategorie A<\/b> machen 80% der Gesamtausgaben der Unternehmen und 20% aller Einkaufskategorien aus;<\/li>\n<li><b>Eink\u00e4ufe der Kategorie B<\/b> machen 15% der Unternehmensausgaben und 30% der Einkaufskategorien aus;<\/li>\n<li><b>Eink\u00e4ufe der Kategorie C <\/b>machen 5% der Ausgaben und 50% der Einkaufskategorien aus.<\/li>\n<\/ol>\n<p>Nach dem Pareto-Prinzip konzentrierte sich die Beschaffungsfunktion auf die Kontrolle der Eink\u00e4ufe, die einen erheblichen Einfluss auf dem Gesamtwert haben, d.h. auf die Eink\u00e4ufe der Kategorie A bzw. der Kategorie B.<\/p>\n<p>So wurden die scheinbar wenig strategischen Eink\u00e4ufe der Kategorie C von den Eink\u00e4ufern lange Zeit vernachl\u00e4ssigt. <b>Die Realit\u00e4t sieht jedoch vielerorts anders aus: <\/b>Obwohl sie nur 5% des Gesamtbetrags der Eink\u00e4ufe ausmachen, sind sie f\u00fcr den Gro\u00dfteil der indirekten Kosten verantwortlich (Lieferantenmanagement, Auftragsvergabe, Kosten f\u00fcr Minderqualit\u00e4t, ungeregelte Eink\u00e4ufe usw.). Die Beschaffungsabteilungen m\u00fcssen diese Einkaufskategorie daher unter dem Blickwinkel der Gesamtbetriebskosten (Total Cost of Acquisition, TCO) angehen.<\/p>\n<p>Daher ist die Optimierung der Eink\u00e4ufe der Kategorie C heute ein Mittel, welches Unternehmen einen Wettbewerbsvorteil verschafft bzw. sogar auf einen gewissen Reifegrad innerhalb ihrer Beschaffungsabteilungen hinweist.<\/p>\n<h2>Wie wendet man das Pareto-Prinzip im Einkauf an?<\/h2>\n<p>Die Anwendung des Pareto-Prinzips in der Beschaffungsstrategie eines Unternehmens erfordert eine echte Projektleitung, indem man einem mehrstufigen Denkansatz folgt.<\/p>\n<h3>Eine Datenbank erstellen<\/h3>\n<p>F\u00fcr die Entscheidungsfindung im Einkauf ist eine genaue Bestandsaufnahme des Einkaufsportfolios unerl\u00e4sslich. Diese Datenbank muss anhand mehrerer Parameter exakt eingerichtet werden.<\/p>\n<p>In einer Tabelle werden die folgenden Daten \u00fcber ein Jahr hinweg angegeben:<\/p>\n<ul>\n<li>Artikelnummer;<\/li>\n<li>Produktfamilie;<\/li>\n<li>Unterfamilie;<\/li>\n<li>Anbieter;<\/li>\n<li>Umsatz (in absteigender Reihenfolge);<\/li>\n<li>Volumen;<\/li>\n<li>Anteil am Gesamtumsatz;<\/li>\n<li>Kumulativer Prozentsatz des Umsatzes.<\/li>\n<\/ul>\n<p>Mithilfe einer solchen Diagnose kann man dann seine ABC-Klassifizierung vornehmen. Wenn der kumulierte Umsatz mehr als 95% betr\u00e4gt, handelt es sich um Eink\u00e4ufe der Kategorie C, betr\u00e4gt er mehr als 80%, handelt es sich um die Kategorie B, ansonsten um Kategorie A. Um die Gesamtsituation gut zu erfassen, kann man zus\u00e4tzlich ein Diagramm erstellen, welches gemeinhin als \u201ePareto-Diagramm\u201c bezeichnet wird.<\/p>\n<p>Hervorzuheben ist, dass es heute automatisierte Managementsysteme gibt, mit denen diese Einstellungen relativ einfach vorgenommen werden k\u00f6nnen, und die damit die digitale Transformation der Beschaffungsabteilungen einleiten.<\/p>\n<h3>Alle Parameter ber\u00fccksichtigen<\/h3>\n<p>Anschlie\u00dfend sollte man sich das erhaltene Mapping genauer ansehen, um die Aufgaben zu priorisieren. Bei der Datenanalyse m\u00fcssen die Herausforderungen des Unternehmens sowie die Marktanforderungen ber\u00fccksichtigt werden, um die Einkaufsstrategie zu entwickeln.<\/p>\n<p>Je nach Art der Aktivit\u00e4t des Unternehmens muss seine Einkaufsabteilung zus\u00e4tzliche Parameter (Preise, Lieferfristen usw.) einbeziehen, welche dar\u00fcber entscheiden, wie viel Aufmerksamkeit bestimmten Anbietern im Vergleich zu anderen geschenkt werden sollte. Ganz oben auf der Liste sollte nat\u00fcrlich die Ermittlung \u201ezentraler\u201c oder \u201ekritischer\u201c Elemente stehen, welche f\u00fcr den Produktionsprozess unerl\u00e4sslich sind, selbst wenn ihr Volumen im Vergleich zum Einkaufsbuch geringf\u00fcgig ist.<\/p>\n<p>Au\u00dferdem ist es wichtig, die Situation jedes einzelnen Anbieters zu ber\u00fccksichtigen: geografische Abgelegenheit, geopolitische Risiken f\u00fcr die Beschaffung, die sich daraus ergeben k\u00f6nnen, das Risiko von Cyberangriffen im Bereich der Lieferkette, eine m\u00f6gliche Monopolstellung bzw. umgekehrt ein starker Wettbewerb auf dem Markt, der sich nicht in gleicher Weise auf die Reaktionszeit in der Produktion auswirkt.<\/p>\n<p>Die ABC-Klassifizierung darf also nicht von der Sicherung der Lieferkette ablenken, die nach wie von grundlegender Bedeutung ist.<\/p>\n<h3>Die einzelnen Rollen festlegen<\/h3>\n<p>Um maximale Effizienz zu gew\u00e4hrleisten, muss die Anwendung des Pareto-Prinzips innerhalb der Teams gut flankiert werden. So muss die Anzahl der Personen, die Zugriff auf die Datenbank haben, begrenzt werden, um eine Streuung zu vermeiden, wodurch die Nutzung der Datenbank wirkungslos w\u00e4re.<\/p>\n<p>Jeder Bereich dieser Datenbank muss zudem genau definierten Rollen in den Abteilungen Einkauf, Beschaffung, Finanzen und Controlling entsprechen. Von Anfang an klar festgelegte Regeln erm\u00f6glichen eine bessere Koordination zwischen den Abteilungen und verhindern potenzielle Missverst\u00e4ndnisse, die sich nachteilig auf Kosten, Verhandlungsmacht oder sogar Lieferzeiten auswirken.<\/p>\n<p>Die Ber\u00fccksichtigung all dieser Elemente r\u00fcckt diese Klassifizierung (A, B und C) in den Vordergrund und ist f\u00fcr die Beschaffungsabteilung eine wertvolle Entscheidungshilfe bei der Optimierung der einzelnen Kategorien.<\/p>\n<p>Die Anwendung des Pareto-Prinzips erm\u00f6glicht es den Beschaffungsabteilungen somit, ihre Ressourcen zu optimieren und ihre Effizienz insgesamt zu verbessern. Mithilfe der ABC-Klassifizierung k\u00f6nnen die Strategie und die Hebel zur Optimierung entsprechend der jeweiligen Kategorie angepasst werden. Schlie\u00dflich kann die <a href=\"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/was-ist-die-kraljic-matrix\/\">Kraljic-Matrix<\/a>, ein weiteres wichtiges Analyse- und Managementinstrument f\u00fcr die Beschaffungsfunktion, diese Klassifizierung erg\u00e4nzen, um die Strategie im Sinne einer kontinuierlichen Verbesserung zu verfeinern.<\/p>\n<p>F\u00fcr weitere Informationen zum Thema, laden Sie unser Whitepaper <a href=\"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/long-tail-ausgaben-6-hebel-zur-optimierung-ihrer-strategie\/\">\u201eEink\u00e4ufe der Kategorie C: 6 Hebel zur Optimierung Ihrer Strategie\u201c<\/a> herunter.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Pareto-Prinzip, auch als 20-80-Regel bekannt, bezieht sich auf eine statistische Regelm\u00e4\u00dfigkeit, die in zahlreichen Bereichen beobachtet wird. Danach werden 80% des Gesamtwerts durch 20% der wichtigsten Posten erzielt. Die Beschaffungsfunktion hat sich dieses Prinzip zu eigen gemacht, um ihre Eink\u00e4ufe nach drei Kategorien (A, B und C) zu ordnen und die damit verbundene Strategie zu optimieren. Dennoch sollte man&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":73628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-72406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intelligentes-und-effizientes-arbeiten"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72406"}],"version-history":[{"count":3,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72406\/revisions"}],"predecessor-version":[{"id":74122,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72406\/revisions\/74122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/73628"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}