{"id":72409,"date":"2023-10-18T07:00:02","date_gmt":"2023-10-18T07:00:02","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72231"},"modified":"2026-01-23T20:33:49","modified_gmt":"2026-01-23T20:33:49","slug":"daten-und-lieferkette-warum-transparenz-beweisen","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/daten-und-lieferkette-warum-transparenz-beweisen\/","title":{"rendered":"Daten und Lieferkette: Warum Transparenz beweisen?"},"content":{"rendered":"<figure class=\"post-hero\">\n        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/01\/Daten_und_Lieferkette_Warum_Transparenz_beweisen.jpg\" alt=\"\" \/><br \/>\n      <\/figure>\n<div class=\"post-content\">\n<p>Im Zeitalter der Digitalisierung sind Daten zum \u201eschwarzen Gold\u201c in der Wirtschaft geworden. Angesichts des zunehmenden Drucks auf die Lieferkette erscheinen Daten als ein gewaltiger Hebel, um die Sichtbarkeit zu verbessern und die Beziehungen zu den Interessengruppen zu st\u00e4rken. Hinter diesem Bed\u00fcrfnis nach mehr Transparenz steht das Bestreben der Unternehmen, ihre Lieferkette zu optimieren, ihr Risikomanagement zu verbessern und ihre Nachhaltigkeitsziele zu erreichen. <\/p>\n<h2>Bestandsaufnahme der Transparenz in der Lieferkette\u00a0<\/h2>\n<p>Laut einer aktuellen Studie mit dem Titel \u201e<i>Data-enabled supply chain transparency\u201c<\/i>, die von Procurement Leaders f\u00fcr Ivalua durchgef\u00fchrt wurde, erachten 77% der Unternehmen die Transparenz der Lieferkette als kritisch oder von gr\u00f6\u00dfter Bedeutung. <\/p>\n<p>Dennoch ist <b>nur<\/b> <b>ein Drittel<\/b> mit dem Grad der Sichtbarkeit, den sie heute haben, <b>zufrieden<\/b> (oder sehr zufrieden). In einer Welt, die zunehmend komplexer, volatiler und unsicherer wird, l\u00e4sst diese Diskrepanz aufhorchen, zumal die meisten Unternehmen \u00fcber ein ausreichendes Budget verf\u00fcgen, um die notwendigen Investitionen in diesem Bereich zu t\u00e4tigen.<\/p>\n<p>W\u00e4hrend die Entscheidungstr\u00e4ger im Einkauf einen guten \u00dcberblick \u00fcber ihre Tier-1-Lieferanten haben, sieht es bei den Unterauftragnehmern (Tier 2, 3, 4 und dar\u00fcber hinaus) ganz anders aus. Dies wirft ernste Fragen in Bezug auf das Risikomanagement auf. 59% der Unternehmen sind heute der Ansicht, dass sie eine zufriedenstellende Sichtbarkeit ihrer Tier-1-Lieferanten haben. Im Gegensatz dazu liegt dieser Prozentsatz bei den Tier-2-Lieferanten nur bei 7% und bei Tier-3-Lieferanten bei 2%. <\/p>\n<hr\/>\n<p><b>Was ist mit dem Begriff \u201eTransparente Lieferkette\u201c gemeint?<\/b><\/p>\n<p>Laut Alexis Bateman, Forscherin und Leiterin des Massachusetts Institute of Technology (MIT), einem Forschungszentrum rund um nachhaltige Lieferketten, beruht die Transparenz der Lieferkette auf zwei Begriffen:<\/p>\n<ul>\n<li>\n<p><b>Sichtbarkeit<\/b>, also die exakte Identifizierung und Erhebung s\u00e4mtlicher Daten der einzelnen Glieder der Lieferkette, und zwar meist in Echtzeit;<\/p>\n<\/li>\n<li>\n<p><b>Offenlegung<\/b>, also die Weitergabe dieser Informationen sowohl intern als auch extern.<\/p>\n<\/li>\n<\/ul>\n<hr\/>\n<h2>Big Data und Lieferkettenmanagement: Vorteile?<\/h2>\n<p>Big Data geh\u00f6rt zu den wichtigsten disruptiven Technologien dieses Jahrhunderts. In Verbindung mit anderen technologischen L\u00f6sungen <i>(Data Analytics<\/i>, <i>Business Intelligence, Machine Learning, Cloud<\/i>, RFID usw.) k\u00f6nnen Unternehmen riesige Datenmengen f\u00fcr den Einkauf und die Lieferkette nutzen.<\/p>\n<h3>Die Produktivit\u00e4t steigern<\/h3>\n<p>Mithilfe von Datenmanagement k\u00f6nnen Unternehmen zun\u00e4chst <b>ihre betriebliche Effizienz steigern<\/b> und gleichzeitig die Kosten senken. Es geht darum, Ereignisse zu identifizieren und vorherzusagen, um den Warenfluss zu optimieren und die gesamte Lieferkette zu kontrollieren.<\/p>\n<h3>Konformit\u00e4t herstellen<\/h3>\n<p>Im Bereich der Transparenz werden <b>die Vorschriften <\/b>im Laufe der Zeit <b>zunehmend versch\u00e4rft<\/b>, z.B. durch den <i>U.K. Modern Slavery Act<\/i>, den <i>California Transparency in Supply Chains Act, <\/i>das franz\u00f6sische Sapin-II-Gesetz oder die EU-Richtlinie \u00fcber die ESG-Berichterstattung (Umwelt, Soziales und Unternehmensf\u00fchrung). <\/p>\n<p>Die Unternehmen m\u00fcssen ihre Wachsamkeit erh\u00f6hen und <i>Ethical Sourcing<\/i> f\u00f6rdern. Eines ist sicher: Diejenigen, die \u00fcber eine gewisse Transparenz entlang ihrer Lieferkette verf\u00fcgen, k\u00f6nnen die Einhaltung der Vorschriften leichter gew\u00e4hrleisten.<\/p>\n<h3>Kundenbeziehung st\u00e4rken<\/h3>\n<p>Eine transparente Lieferkette erm\u00f6glicht es Unternehmen, die Kundenbeziehung zu st\u00e4rken. Zun\u00e4chst sorgen sie f\u00fcr eine <b>h\u00f6here Zufriedenheit der Verbraucher<\/b>, wenn sie k\u00fcnftig bei ihrer Produktwahl die Herkunft, die Zusammensetzung, die Produktions- und Herstellungsbedingungen sowie die \u00f6kologischen Auswirkungen ber\u00fccksichtigen. <\/p>\n<p>Laut einer aktuellen Umfrage von Avery Dennison legen zwei von f\u00fcnf K\u00e4ufern Wert auf die transparente R\u00fcckverfolgbarkeit der von ihnen gekauften Kleidungsst\u00fccke. Durch das Angebot eines solchen Informationszugangs gewinnen die Marken au\u00dferdem <b>das Vertrauen ihrer Kunden und st\u00e4rken die Kundenbindung.<\/b><\/p>\n<h3>Partnerschaften ausbauen<\/h3>\n<p>Ein solches Vorgehen st\u00e4rkt auch die Beziehungen zu anderen Interessengruppen, n\u00e4mlich den Gesch\u00e4ftspartnern. Transparenz schafft <b>Vertrauen<\/b> zwischen der Beschaffungsabteilung, ihren Anbietern und Dienstleistern, zumal dadurch die Bindung zu Gleichgesinnten verst\u00e4rkt und <b>damit ein positiver Kreislauf<\/b> in Gang gesetzt wird.<\/p>\n<h2>Wie kann Transparenz innerhalb der Lieferkette gew\u00e4hrleistet werden?<\/h2>\n<p>Um die Digitalisierung des Einkaufs zu beschleunigen und die Transparenz innerhalb der Lieferkette zu erh\u00f6hen, m\u00fcssen Unternehmen drei gro\u00dfe Herausforderungen rund um Daten und Talente bew\u00e4ltigen.<\/p>\n<h3>1. Die Qualit\u00e4t der Daten<\/h3>\n<p>Die Hauptschwierigkeit bei der Verbesserung der Transparenz der Lieferkette ist die Qualit\u00e4t der Daten. Und das aus gutem Grund: <b>81% der Entscheidungstr\u00e4ger im Einkauf f\u00fchren dies als eine gro\u00dfe Herausforderung an.<\/b> Dieser Aspekt wird anhand mehrerer Kriterien bewertet: <\/p>\n<ul>\n<li>\n<p>Genauigkeit;<\/p>\n<\/li>\n<li>\n<p>Vollst\u00e4ndigkeit; <\/p>\n<\/li>\n<li>\n<p>Homogenit\u00e4t; <\/p>\n<\/li>\n<li>\n<p>Zuverl\u00e4ssigkeit;<\/p>\n<\/li>\n<li>\n<p>Aktualit\u00e4t;<\/p>\n<\/li>\n<li>\n<p>Sicherheit der Daten. <\/p>\n<\/li>\n<\/ul>\n<p>Daten von \u201ehoher Qualit\u00e4t\u201c m\u00fcssen au\u00dferdem der beabsichtigten Nutzung entsprechen. Um dieses Problem zu bew\u00e4ltigen, sind die Entscheidungstr\u00e4ger im Einkauf bestrebt, vor allem in geeignete Tools zu investieren und einzelne Initiativen zur Bereinigung gro\u00dfer Datenmengen zu ergreifen.<\/p>\n<h3>2. Die Zug\u00e4nglichkeit der Daten <\/h3>\n<p>Auch heute noch st\u00fctzen sich Unternehmen auf Datenquellen, die konventionell erscheinen m\u00f6gen (Vertr\u00e4ge, Rechnungen, Audits usw.). Dies ist f\u00fcr Beschaffungsabteilungen jedoch nicht ausreichend, um die erforderlichen Analysen vorzunehmen und Entscheidungen zu treffen. <\/p>\n<p>Beispielsweise haben nur 19% der Beschaffungsabteilungen Zugang zu Informationen \u00fcber ihre Scope-3-Treibhausgasemissionen. Unter diesen Voraussetzungen ist ihnen ein effizientes Handeln in Sachen CO<sub>2<\/sub>-Fu\u00dfabdruck nicht m\u00f6glich. <b>K\u00fcnftig werden weitere Quellen genutzt werden<\/b>, um die Sichtbarkeit zu erh\u00f6hen, wie z.B. <i>Market Intelligence Tools <\/i>oder Dritte.<\/p>\n<h3>3. Der Fachkr\u00e4ftemangel<\/h3>\n<p>Ob f\u00fcr die Sammlung, Verwaltung oder Analyse von Daten: Unternehmen brauchen qualifizierte Arbeitskr\u00e4fte. Es ist zwar wichtig, dass die Fachteams in der Lage sind, ihre Kompetenzen in diesem Bereich zu erweitern, aber die Unternehmen haben auch ein Interesse daran, <b>Experten <\/b>f\u00fcr <i>Data Science <\/i>oder <i>Data Management<\/i> <b>einzustellen<\/b><i> (Data Scientists, Data Analysts <\/i>usw.). Die beiden Funktionen m\u00fcssen dann nur ihr Know-how kombinieren, um fundierte Entscheidungen zu treffen.   <\/p>\n<p>F\u00fcr die Lieferkette sind Daten daher ein gro\u00dfes Plus. Richtig genutzt, stellen sie einen gewaltigen Hebel f\u00fcr die <b>Wettbewerbsf\u00e4higkeit, Widerstandskraft und Nachhaltigkeit<\/b> der Unternehmen dar.\u00a0<\/p>\n<\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/01\/Daten_und_Lieferkette_Warum_Transparenz_beweisen_2.jpg\" alt=\"\" \/><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Zeitalter der Digitalisierung sind Daten zum \u201eschwarzen Gold\u201c in der Wirtschaft geworden. Angesichts des zunehmenden Drucks auf die Lieferkette erscheinen Daten als ein gewaltiger Hebel, um die Sichtbarkeit zu verbessern und die Beziehungen zu den Interessengruppen zu st\u00e4rken. Hinter diesem Bed\u00fcrfnis nach mehr Transparenz steht das Bestreben der Unternehmen, ihre Lieferkette zu optimieren, ihr Risikomanagement zu verbessern und ihre&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":57222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-72409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intelligentes-und-effizientes-arbeiten"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72409"}],"version-history":[{"count":1,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72409\/revisions"}],"predecessor-version":[{"id":73013,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72409\/revisions\/73013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/57222"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}