{"id":72542,"date":"2024-08-08T10:00:02","date_gmt":"2024-08-08T10:00:02","guid":{"rendered":"https:\/\/app-mde-blog-prd.azurewebsites.net\/?p=72326"},"modified":"2026-02-12T10:28:10","modified_gmt":"2026-02-12T10:28:10","slug":"beispiel-fuer-eine-verantwortungsvolle-beschaffungspolitik-wie-kann-man","status":"publish","type":"post","link":"https:\/\/www.manutan.de\/blog\/intelligentes-und-effizientes-arbeiten\/beispiel-fuer-eine-verantwortungsvolle-beschaffungspolitik-wie-kann-man\/","title":{"rendered":"Beispiel f\u00fcr eine verantwortungsvolle Beschaffungspolitik: Wie kann man seine Einkaufsstrategie umgestalten?"},"content":{"rendered":"<figure class=\"post-hero\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-73491 size-full\" src=\"\/wp-content\/uploads\/2024\/08\/Beispiel_fur_eine_verantwortungsvolle_Beschaffungspolitik_Wie_kann_man_seine_Einkaufsstrategie_umgestalten.png\" alt=\"\" width=\"717\" height=\"478\" srcset=\"\/wp-content\/uploads\/2024\/08\/Beispiel_fur_eine_verantwortungsvolle_Beschaffungspolitik_Wie_kann_man_seine_Einkaufsstrategie_umgestalten.png 717w, \/wp-content\/uploads\/2024\/08\/Beispiel_fur_eine_verantwortungsvolle_Beschaffungspolitik_Wie_kann_man_seine_Einkaufsstrategie_umgestalten-300x200.png 300w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/><\/figure>\n<div class=\"post-content\">\n<p>Angesichts des wachsenden kollektiven Bewusstseins verpflichten sich viele Unternehmen, eine nachhaltige Zukunft zu unterst\u00fctzen. Vor diesem Hintergrund \u00e4ndern sie ihre Einkaufsstrategie im Einklang mit ihrem <a href=\"https:\/\/www.manutan.de\/de\/oid\/csr-ansatz\">CSR-Engagement<\/a> (<i>Corporate Social Responsibility<\/i>). Als enormer Hebel f\u00fcr Wettbewerbsf\u00e4higkeit, Widerstandsf\u00e4higkeit und langfristige Differenzierung erweist sich die Einf\u00fchrung einer verantwortungsvollen Beschaffungspolitik daher als unumg\u00e4nglich.<\/p>\n<h2>Definition und Pfeiler einer verantwortungsvollen Beschaffungspolitik<\/h2>\n<p>Eine verantwortungsvolle Beschaffungspolitik soll sicherstellen, dass ein Unternehmen beim Einkauf von Waren und\/oder Dienstleistungen <b>seine negativen Auswirkungen<\/b> auf Umwelt und Gesellschaft <b>minimiert<\/b> und <b>seine positiven Auswirkungen verst\u00e4rkt<\/b>. Somit erf\u00fcllt eine verantwortungsvolle Beschaffung Kriterien, die sich auf die nachhaltige Entwicklung beziehen, bei gleichzeitiger Ber\u00fccksichtigung der Lebenszykluskosten.<\/p>\n<p>Konkreter gesagt geh\u00f6rt zu einer verantwortungsvollen Beschaffungspolitik u.a.:<\/p>\n<ul>\n<li>Die Verpflichtungserkl\u00e4rung des Unternehmens<\/li>\n<li>Die Ziele und die Funktionsprinzipien<\/li>\n<li>Die Verantwortlichkeiten und die Rolle jedes Einzelnen<\/li>\n<li>Der Anwendungsbereich<\/li>\n<li>Die Kriterien f\u00fcr die Auswahl der Produkte und Anbieter<\/li>\n<li>Der Implementierungsprozess usw.<\/li>\n<\/ul>\n<p>In diesem Zusammenhang m\u00fcssen die Einkaufsabteilungen drei zentrale Herausforderungen miteinander in Einklang bringen:<\/p>\n<ol>\n<li><b>\u00d6kologisch<\/b>: Ressourcenschonung, Energieeffizienz, Abfallverringerung, Lebensdauer der Produkte usw.<\/li>\n<li><b>Ethisch und gesellschaftlich<\/b>: Achtung der Menschenrechte, Arbeitsbedingungen, Vielfalt, Integration usw.<\/li>\n<li><b>Wirtschaftlich<\/b>: Kosten, Produktqualit\u00e4t, Lieferzeiten usw.<\/li>\n<\/ol>\n<hr \/>\n<p>EcoVadis, eine Plattform f\u00fcr die Bewertung und gemeinsame Nutzung von CSR-Leistungen, definiert verantwortungsvolle Beschaffung als <i>\u201edie \u00dcbernahme und Integration von <\/i><i><b>Grunds\u00e4tzen nachhaltiger Entwicklung<\/b><\/i><i> in Beschaffungsprozesse und -entscheidungen, wobei sichergestellt wird, dass die Anforderungen des Unternehmens und seiner Stakeholder erf\u00fcllt werden. Dies umfasst sowohl die Nachhaltigkeit von Produkten und Materialien als auch die Verantwortung f\u00fcr die Praktiken der Lieferanten<\/i>.\u201c<\/p>\n<hr \/>\n<h2>Warum sollte man eine Politik der verantwortungsvollen Beschaffung einf\u00fchren?<\/h2>\n<p>Die Umsetzung einer verantwortungsvollen Beschaffungspolitik ist eine Antwort auf die drei gro\u00dfen Herausforderungen eines Unternehmens: Kosten, Einhaltung von Vorschriften und Markenimage.<\/p>\n<h3>Die Kosten unter Kontrolle halten<\/h3>\n<p>Dies dient vor allem dazu, die Ausgaben langfristig zu optimieren. Das k\u00f6nnen direkte Einsparungen sein, beispielsweise durch den Kauf energiesparender Produkte, oder auch indirekte Einsparungen, beispielsweise durch die Verwendung recycelter Materialien, um die Produktionskosten zu senken.<\/p>\n<h3>Regelungen antizipieren<\/h3>\n<p>Seit einigen Jahren nehmen die Umweltvorschriften zu: <i>Corporate Sustainability Reporting Directive<\/i>, digitaler Produktpass&#8230; Die Einf\u00fchrung einer verantwortungsvollen Beschaffungspolitik erm\u00f6glicht es, sich an k\u00fcnftige Normen anzupassen, die Einhaltung von Vorschriften zu gew\u00e4hrleisten und die Risiken zu verringern.<\/p>\n<h3>Das Markenimage verbessern<\/h3>\n<p>Schlie\u00dflich wirkt sich eine verantwortungsvolle Beschaffungspolitik positiv auf das Markenimage sowie auf die Beziehungen zu allen Stakeholdern aus. So kann man das eigene Unternehmen auf dem Markt differenzieren, aber auch Kunden, Lieferanten sowie neue Talente anziehen.<\/p>\n<p>Letztendlich tr\u00e4gt dies dazu bei, einen Mehrwert zu schaffen, die Wettbewerbsf\u00e4higkeit zu erh\u00f6hen und den Umsatz der Unternehmen nachhaltig zu steigern.<\/p>\n<h2>Savin&#8217;side\u00ae: eine bew\u00e4hrte Methode<\/h2>\n<p>Die Manutan-Gruppe hat die <a href=\"https:\/\/www.manutan.de\/de\/oid\/savinside\">Savin&#8217;side\u00ae-Methode<\/a> entwickelt, um Unternehmen bei der Optimierung ihrer Einkaufsstrategie f\u00fcr C-Artikel zu unterst\u00fctzen. Diese Methode beruht auf einer Datenanalyse, einem Lean-Ansatz und einem agilen Rahmen. Zu den verschiedenen Schwerpunkten geh\u00f6rt auch die verantwortungsvolle Beschaffung. Diese Methode ist in drei Hauptphasen gegliedert.<\/p>\n<h3>1. Das Audit<\/h3>\n<p>Am Anfang steht die Analyse der Verbrauchsdaten des Unternehmens und der Markttrends. Im vorliegenden Fall geht es vor allem um die Verbrauchsrate <a href=\"https:\/\/www.manutan.de\/de\/oid\/nachhaltige-produkte\">umweltfreundlicher Produkte<\/a>. Ausgehend von den ermittelten Verbesserungsm\u00f6glichkeiten werden ein Fortschrittsplan und die dazugeh\u00f6rigen Leistungsindikatoren festgelegt.<\/p>\n<h3>2. Der Ma\u00dfnahmenplan<\/h3>\n<p>In einem zweiten Schritt muss ein ma\u00dfgeschneiderter Ma\u00dfnahmenplan (Ressourcen, Planung, Koordination) umgesetzt werden. Hier geht es vor allem darum, mit den internen Kunden zu kommunizieren und die digitalen Werkzeuge anzupassen.<\/p>\n<h3>3. Steuerung und Verbesserungen<\/h3>\n<p>Schlie\u00dflich bedarf dieses Vorgehen auch einer kontinuierlichen Verbesserung. Deshalb sollte ein Monitoringsystem eingerichtet werden, um die Aktivit\u00e4ten zu steuern und notwendige Korrekturma\u00dfnahmen einzuleiten.<\/p>\n<h2>Fallstudie eines Erzeugers erneuerbarer Energien<\/h2>\n<p>In dieser Fallstudie geht es um ein Unternehmen, das sich auf erneuerbare Energien spezialisiert hat. Es t\u00e4tigt Ausgaben von mehr als 2 Mio. Euro bei Manutan und verf\u00fcgt \u00fcber einen elektronischen <i>Punch-out<\/i>-Katalog.<\/p>\n<h3>1. Das Audit<\/h3>\n<p>Der <i>Lead-Buyer<\/i> dieses Unternehmens hat sich mit uns in Verbindung gesetzt, um durch seine Produktauswahl seine verantwortungsvolle Beschaffungspolitik zu unterst\u00fctzen. Wir haben uns mit ihm ausgetauscht, um seine Kriterien f\u00fcr verantwortungsvolle Beschaffung (CO<sub>2<\/sub>-Fu\u00dfabdruck, Erhaltung von Ressourcen usw.) zu verstehen und potenzielle L\u00f6sungen zu erarbeiten. Er teilt unsere Definition eines umweltfreundlichen Produkts und m\u00f6chte den Konsum solcher Waren unterst\u00fctzen, indem er auf bestehende Instrumente zur\u00fcckgreift.<\/p>\n<hr \/>\n<p>Bei Manutan betrachten wir ein Produkt als <a href=\"https:\/\/www.manutan.de\/de\/oid\/csr-ansatz\">\u201eumweltfreundlich\u201c<\/a>, wenn es aus zweiter Hand stammt, d.h. gebraucht oder wiederaufbereitet ist, und\/oder zu mindestens 25% aus recyceltem Material besteht und\/oder ein anerkanntes Umweltsiegel besitzt.<\/p>\n<hr \/>\n<p>Bei der Analyse seiner Daten stellen wir fest, dass die aktuelle Verbrauchsrate umweltfreundlicher Produkte bei 9% liegt. Wir haben uns somit auf die am h\u00e4ufigsten wiederkehrenden Eink\u00e4ufe (Volumen und H\u00e4ufigkeit) konzentriert, um ihm umweltfreundliche Alternativen zu den derzeit konsumierten Produkten anzubieten.<\/p>\n<p>Parallel dazu haben wir auch den Konsum umweltfreundlicher Produkte von Unternehmen in derselben Branche untersucht, um weitere potenzielle Verbesserungsbereiche zu identifizieren.<\/p>\n<h3>2. Der Ma\u00dfnahmenplan<\/h3>\n<p>Nachdem wir diese Erkenntnisse mit dem <i>Lead-Buyer<\/i> geteilt haben, haben wir wichtige Ma\u00dfnahmen eingeleitet, um den Schwerpunkt auf ein umweltfreundliches Angebot zu legen:<\/p>\n<ul>\n<li>Es wurde <b>eine Mitteilung<\/b> an die Nutzer versandt, in der das ihnen zur Verf\u00fcgung stehende umweltfreundliche Angebot hervorgehoben wurde, aber auch, wie sie auf diese Produkte in ihrem <i>Punch-out<\/i>-Katalog zugreifen k\u00f6nnen.<\/li>\n<li>Im <i>Punch-out<\/i>-Katalog wurde <b>ein eigener Bereich<\/b> eingerichtet, der die bevorzugten umweltfreundlichen Produkte enth\u00e4lt (gemeinhin als <i>Shop-in-Shop<\/i> bezeichnet).<\/li>\n<\/ul>\n<h3>3. Steuerung und Verbesserungen<\/h3>\n<p>Wir haben ein Tracking-System in Form einer viertelj\u00e4hrlichen <i>Berichterstattung<\/i> eingerichtet. Sechs Monate sp\u00e4ter k\u00f6nnen wir feststellen, dass das Unternehmen seinen Anteil an umweltfreundlichen Produkten erh\u00f6ht hat (+1 Punkt). Diese Ma\u00dfnahmen sollten sich in den kommenden Monaten weiterhin positiv auswirken.<\/p>\n<p>F\u00fcr Unternehmen, die sich dem \u00f6kologischen Wandel verschrieben haben, ist die Einf\u00fchrung einer verantwortungsvollen Beschaffungspolitik unverzichtbar. Durch ein solches Vorgehen werden sie ihren wirtschaftlichen, \u00f6kologischen und gesellschaftlichen Herausforderungen gerecht. Mit einem wohl\u00fcberlegten Ansatz, bew\u00e4hrten Methoden und konkreten Beispielen k\u00f6nnen die Entscheidungstr\u00e4ger verantwortungsvolle Beschaffungspraktiken integrieren, die sich sowohl auf ihr Unternehmen als auch auf die Gesellschaft als Ganzes positiv auswirken.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Angesichts des wachsenden kollektiven Bewusstseins verpflichten sich viele Unternehmen, eine nachhaltige Zukunft zu unterst\u00fctzen. Vor diesem Hintergrund \u00e4ndern sie ihre Einkaufsstrategie im Einklang mit ihrem CSR-Engagement (Corporate Social Responsibility). Als enormer Hebel f\u00fcr Wettbewerbsf\u00e4higkeit, Widerstandsf\u00e4higkeit und langfristige Differenzierung erweist sich die Einf\u00fchrung einer verantwortungsvollen Beschaffungspolitik daher als unumg\u00e4nglich. Definition und Pfeiler einer verantwortungsvollen Beschaffungspolitik Eine verantwortungsvolle Beschaffungspolitik soll sicherstellen, dass&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":73491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-72542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intelligentes-und-effizientes-arbeiten"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/comments?post=72542"}],"version-history":[{"count":3,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72542\/revisions"}],"predecessor-version":[{"id":74089,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/posts\/72542\/revisions\/74089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media\/73491"}],"wp:attachment":[{"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/media?parent=72542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/categories?post=72542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manutan.de\/blog\/wp-json\/wp\/v2\/tags?post=72542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}